{"id":243,"count":12,"description":"","link":"https:\/\/test.cosysunday.com\/de\/product-category\/knitwear-women-de\/","name":"Strickwaren","slug":"knitwear-women-de","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Damenstrick online kaufen - COSY SUNDAY<\/title>\n<meta name=\"description\" content=\"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.\" \/>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Damenstrick online kaufen - COSY SUNDAY\" \/>\n<meta property=\"og:description\" content=\"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/\" \/>\n<meta property=\"og:site_name\" content=\"COSY SUNDAY\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/test.cosysunday.com\\\/de\\\/produkt-kategorie\\\/knitwear-women-de\\\/\",\"url\":\"https:\\\/\\\/test.cosysunday.com\\\/de\\\/produkt-kategorie\\\/knitwear-women-de\\\/\",\"name\":\"Damenstrick online kaufen - COSY SUNDAY\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/test.cosysunday.com\\\/#website\"},\"description\":\"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/test.cosysunday.com\\\/de\\\/produkt-kategorie\\\/knitwear-women-de\\\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/test.cosysunday.com\\\/de\\\/produkt-kategorie\\\/knitwear-women-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430\",\"item\":\"https:\\\/\\\/test.cosysunday.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Strickwaren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/test.cosysunday.com\\\/#website\",\"url\":\"https:\\\/\\\/test.cosysunday.com\\\/\",\"name\":\"COSY SUNDAY\",\"description\":\"Luxury weekend fashion\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/test.cosysunday.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Damenstrick online kaufen - COSY SUNDAY","description":"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Damenstrick online kaufen - COSY SUNDAY","og_description":"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.","og_url":"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/","og_site_name":"COSY SUNDAY","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/","url":"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/","name":"Damenstrick online kaufen - COSY SUNDAY","isPartOf":{"@id":"https:\/\/test.cosysunday.com\/#website"},"description":"Erleben Sie Gem\u00fctlichkeit mit unserer Auswahl an Damen-Strickwaren bei COSY SUNDAY. Mit unseren warmen und stilvollen Optionen k\u00f6nnen Sie Ihren Komfort durch stilvolle Strickjacken erh\u00f6hen.","breadcrumb":{"@id":"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"https:\/\/test.cosysunday.com\/de\/produkt-kategorie\/knitwear-women-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0413\u043b\u0430\u0432\u043d\u0430\u044f \u0441\u0442\u0440\u0430\u043d\u0438\u0446\u0430","item":"https:\/\/test.cosysunday.com\/de\/"},{"@type":"ListItem","position":2,"name":"Strickwaren"}]},{"@type":"WebSite","@id":"https:\/\/test.cosysunday.com\/#website","url":"https:\/\/test.cosysunday.com\/","name":"COSY SUNDAY","description":"Luxury weekend fashion","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.cosysunday.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/test.cosysunday.com\/de\/wp-json\/wp\/v2\/product_cat\/243","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/test.cosysunday.com\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/test.cosysunday.com\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/test.cosysunday.com\/de\/wp-json\/wp\/v2\/product?product_cat=243"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}